{"id":3142,"date":"2015-02-02T08:25:17","date_gmt":"2015-02-02T11:25:17","guid":{"rendered":"http:\/\/blog.dialhost.com.br\/?p=3142"},"modified":"2015-02-02T08:25:17","modified_gmt":"2015-02-02T11:25:17","slug":"23-motivos-para-investir-em-automacao-de-marketing","status":"publish","type":"post","link":"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/","title":{"rendered":"23 motivos para investir em automa\u00e7\u00e3o de marketing"},"content":{"rendered":"<p>\t\t\t\tMarketing de conte\u00fado deixou de ser tend\u00eancia para se tornar realidade por mostrar, ano ap\u00f3s ano, que \u00e9 capaz de gerar resultados por aumentar a credibilidade e criar um v\u00ednculo mais forte e duradouro com o p\u00fablico. Nos EUA, empresas que utilizam o marketing de conte\u00fado obtiveram o dobro de leads em compara\u00e7\u00e3o com as que n\u00e3o utilizam, a um custo quase um ter\u00e7o menor. No Brasil, apenas as grandes companhias vem investindo em estrat\u00e9gias de conte\u00fado. As pequenas e m\u00e9dias empresas, justamente as que mais teriam a ganhar, ainda resistem em utiliz\u00e1-la. A partir de um estudo realizado pela Newscred, reunimos abaixo 23 dados e estat\u00edsticas para ajud\u00e1-lo na sua decis\u00e3o de incluir o content marketing em seu or\u00e7amento para 2015.<\/p>\n<p>78% dos executivos de marketing consideram o conte\u00fado como o futuro do marketing;<br \/>\n79% das empresas est\u00e3o adotando estrat\u00e9gias de conte\u00fado como forma de fortalecer suas marcas;<br \/>\n70% dos executivos de marketing consideram conte\u00fado mais efetivo que an\u00fancios em revistas, mala direta, assessoria de imprensa e rela\u00e7\u00f5es p\u00fablicas;<br \/>\n92% dos profissionais de marketing B2B usam estrat\u00e9gias de marketing de conte\u00fado. No B2C s\u00e3o 82%;<br \/>\nBlogs geram 434% mais indexa\u00e7\u00e3o de p\u00e1ginas e 97% mais indexa\u00e7\u00e3o de links no Google;<br \/>\n37% dos executivos de marketing afirmam que o blog \u00e9 o que mais agrega valor para o marketing;<br \/>\nEmpresas cujos blogs s\u00e3o abastecidos diariamente geram cinco vezes mais tr\u00e1fego para o site do que empresas que n\u00e3o possuem blogs;<br \/>\nEmpresas com blogs ativos conseguem gerar 97% mais leads;<br \/>\nConte\u00fado de qualidade aumenta engajamento e lealdade \u00e0 marca;<br \/>\nConte\u00fado interessante \u00e9 uma das tr\u00eas principais raz\u00f5es pelas quais as pessoas seguem marcas nas redes sociais;<br \/>\n70% dos consumidores preferem conhecer marcas e empresas por meio de conte\u00fado do que em an\u00fancios;<br \/>\n78% dos consumidores acreditam que empresas que produzem conte\u00fado de qualidade est\u00e3o interessadas em estabelecer bom relacionamento com seu p\u00fablico;<br \/>\n68% dos consumidores gastam o seu tempo com conte\u00fado de marcas com as quais est\u00e3o interessados;<br \/>\n60% dos consumidores passam a ter uma vis\u00e3o mais positiva da empresa ap\u00f3s ler seu conte\u00fado no site;<br \/>\n58% dos consumidores acreditam em conte\u00fado editorial;<br \/>\n46% das pessoas afirmam que o layout do site \u00e9 o crit\u00e9rio n\u00famero 1 para avaliar a credibilidade de uma empresa;<br \/>\nPosts com v\u00eddeos atraem 3 vezes mais links do que textos;<br \/>\n57% dos executivos de marketing B2B consideram SEO o maior gerador de leads e que a cria\u00e7\u00e3o de conte\u00fado \u00e9 a estrat\u00e9gia mais efetiva de SEO atualmente;<br \/>\nPossibilidade do consumidor avaliar e fazer resenhas dos produtos aumenta a taxa de convers\u00e3o em 105%;<br \/>\nConsumidores que recebem e-mail marketing gastam 83% mais em suas compras;<br \/>\nExecutivos de marketing investem 1\/3 de seu or\u00e7amento em conte\u00fado;<br \/>\n54% dos executivos de marketing afirmam que aumentar\u00e3o seu or\u00e7amento para conte\u00fado nos pr\u00f3ximos 12 meses;<br \/>\nPara obter os mesmos resultados, o marketing de conte\u00fado necessita de investimento 62% menor do que em a\u00e7\u00f5es tradicionais de propaganda.<\/p>\n<p>&#8212;-<\/p>\n<p>Artigo publicado no <a href=\"http:\/\/imasters.com.br\/midia-e-marketing-digital\/23-motivos-para-investir-em-automacao-de-marketing\/\" target=\"_blank\" rel=\"noopener noreferrer\">iMasters<\/a>.\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\t\t\t\tMarketing de conte\u00fado deixou de ser tend\u00eancia para se tornar realidade por mostrar, ano ap\u00f3s ano, que \u00e9 capaz de gerar resultados por aumentar a credibilidade e criar um v\u00ednculo mais forte e duradouro com o p\u00fablico. \t\t\t\t<\/p>\n","protected":false},"author":1,"featured_media":7619,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3,5],"tags":[62,99,146,158],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>23 motivos para investir em automa\u00e7\u00e3o de marketing - Blog DialHost<\/title>\n<meta name=\"description\" content=\"Marketing de conte\u00fado deixou de ser tend\u00eancia para se tornar realidade por mostrar que \u00e9 capaz de gerar resultados por aumentar a credibilidade\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"23 motivos para investir em automa\u00e7\u00e3o de marketing - Blog DialHost\" \/>\n<meta property=\"og:description\" content=\"Marketing de conte\u00fado deixou de ser tend\u00eancia para se tornar realidade por mostrar que \u00e9 capaz de gerar resultados por aumentar a credibilidade\" \/>\n<meta property=\"og:url\" content=\"\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog DialHost\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/DialHost\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/DialHost\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-02T11:25:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dialhost.com.br\/blog\/wp-content\/uploads\/2015\/02\/content-marketing.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"260\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dialhost\" \/>\n<meta name=\"twitter:site\" content=\"@dialhost\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#organization\",\"name\":\"DialHost Internet\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/\",\"sameAs\":[\"http:\/\/www.facebook.com\/DialHost\",\"https:\/\/www.instagram.com\/dialhost_oficial\/\",\"https:\/\/www.linkedin.com\/company\/dialhost-internet\",\"https:\/\/www.youtube.com\/channel\/UCAiqiX8IiqTSfA8wQhpzgXQ\",\"https:\/\/twitter.com\/dialhost\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/wp-content\/uploads\/2019\/03\/marca-dialhost.png\",\"width\":81,\"height\":81,\"caption\":\"DialHost Internet\"},\"image\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#website\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/\",\"name\":\"Blog DialHost\",\"description\":\"Os melhores conte\\u00fados sobre Desenvolvimento Web, Marketing e Neg\\u00f3cios\",\"publisher\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.dialhost.com.br\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/wp-content\/uploads\/2015\/02\/content-marketing.jpg\",\"width\":700,\"height\":260,\"caption\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/#webpage\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/\",\"name\":\"23 motivos para investir em automa\\u00e7\\u00e3o de marketing - Blog DialHost\",\"isPartOf\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/#primaryimage\"},\"datePublished\":\"2015-02-02T11:25:17+00:00\",\"dateModified\":\"2015-02-02T11:25:17+00:00\",\"description\":\"Marketing de conte\\u00fado deixou de ser tend\\u00eancia para se tornar realidade por mostrar que \\u00e9 capaz de gerar resultados por aumentar a credibilidade\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"\/blog\/\",\"url\":\"\/blog\/\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/\",\"url\":\"\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/\",\"name\":\"23 motivos para investir em automa\\u00e7\\u00e3o de marketing\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#\/schema\/person\/a0b10cbe35449dea173a06d4664f9fcc\"},\"headline\":\"23 motivos para investir em automa\\u00e7\\u00e3o de marketing\",\"datePublished\":\"2015-02-02T11:25:17+00:00\",\"dateModified\":\"2015-02-02T11:25:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/#webpage\"},\"publisher\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/23-motivos-para-investir-em-automacao-de-marketing\/#primaryimage\"},\"keywords\":\"content marketing,feed de parceiros,marketing,noticias\",\"articleSection\":\"Dicas e Not\\u00edcias,Marketing\",\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#\/schema\/person\/a0b10cbe35449dea173a06d4664f9fcc\",\"name\":\"DialHost Internet\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05feec2f99aef1c42b09aeaa637ee66f?s=96&r=g\",\"caption\":\"DialHost Internet\"},\"description\":\"H\\u00e1 mais de 18 anos proporcionando um servi\\u00e7o de hospedagem de sites voltado 100% na Experi\\u00eancia e Sucesso do Cliente, prezando a qualidade, transpar\\u00eancia e seguran\\u00e7a.\",\"sameAs\":[\"https:\/\/www.facebook.com\/DialHost\",\"https:\/\/www.instagram.com\/dialhost_oficial\/\",\"https:\/\/www.linkedin.com\/company\/dialhost-internet\",\"https:\/\/twitter.com\/dialhost\",\"https:\/\/www.youtube.com\/channel\/UCAiqiX8IiqTSfA8wQhpzgXQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/posts\/3142"}],"collection":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/comments?post=3142"}],"version-history":[{"count":0,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/posts\/3142\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/media\/7619"}],"wp:attachment":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/media?parent=3142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/categories?post=3142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/tags?post=3142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}