{"id":2772,"date":"2014-09-22T10:08:53","date_gmt":"2014-09-22T13:08:53","guid":{"rendered":"http:\/\/blog.dialhost.com.br\/?p=2772"},"modified":"2014-09-22T10:08:53","modified_gmt":"2014-09-22T13:08:53","slug":"dicas-para-aprender-mais-com-testes-ab","status":"publish","type":"post","link":"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/","title":{"rendered":"Dicas para aprender mais com testes A\/B"},"content":{"rendered":"<figure id=\"attachment_2773\" aria-describedby=\"caption-attachment-2773\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/blog.dialhost.com.br\/wp-content\/uploads\/2014\/09\/ab.jpg\"><img loading=\"lazy\" class=\"size-full wp-image-2773\" src=\"http:\/\/blog.dialhost.com.br\/wp-content\/uploads\/2014\/09\/ab.jpg\" alt=\"imagem ilustrativa\" width=\"700\" height=\"260\" \/><\/a><figcaption id=\"caption-attachment-2773\" class=\"wp-caption-text\">imagem ilustrativa<\/figcaption><\/figure>\n<p>Decifrar o comportamento do consumidor, suas prefer\u00eancias e escolhas, certamente \u00e9 uma tarefa extremamente dif\u00edcil. Embora existam diversos estudos acad\u00eamicos sobre o assunto, al\u00e9m de in\u00fameros cases de sucesso na \u00e1rea de comunica\u00e7\u00e3o e marketing para usarmos como refer\u00eancia, na maioria dos casos a efic\u00e1cia de uma campanha nessas duas \u00e1reas s\u00f3 pode ser avaliada com precis\u00e3o a partir do feedback do pr\u00f3prio p\u00fablico. Isso n\u00e3o significa dizer, no entanto, que a empresa deva assumir uma postura passiva.<\/p>\n<p>Uma das estrat\u00e9gias mais recomendadas para aprimorar a efic\u00e1cia das a\u00e7\u00f5es de comunica\u00e7\u00e3o e marketing de uma organiza\u00e7\u00e3o, aumentando, assim, as taxas de convers\u00e3o, \u00e9 a realiza\u00e7\u00e3o de testes A\/B. Cores dos bot\u00f5es de compra, palavras-chave utilizadas, Layouts, CTAs (Call to Action), enfim, \u00e9 poss\u00edvel avaliar, atrav\u00e9s de experimentos, quais s\u00e3o os elementos que mais atraem o consumidor nas pe\u00e7as enviadas pela empresa. Nesse artigo, voc\u00ea conhecer\u00e1 quatro dicas para aprimorar o seu aprendizado durante a realiza\u00e7\u00e3o desses testes. Confira!<\/p>\n<p><strong>1. Fa\u00e7a testes minuciosos<\/strong><\/p>\n<p>Quando uma campanha n\u00e3o rende o esperado, \u00e9 muito comum que seja feita uma renova\u00e7\u00e3o completa na pe\u00e7a enviada para o p\u00fablico. No entanto, nem sempre essa \u00e9 a melhor alternativa, e por isso a import\u00e2ncia de se realizar testes A\/B. Em muitos dos casos, trocar apenas uma palavra, como \u201cpromo\u00e7\u00e3o\u201d no lugar de \u201cdesconto\u201d, pode mudar bastante o n\u00famero de convers\u00f5es realizadas com a estrat\u00e9gia.<\/p>\n<p>Por isso, antes de repaginar o material enviado, opte por fazer pequenas mudan\u00e7as e acompanhar a rea\u00e7\u00e3o do p\u00fablico \u00e0 elas. \u00c9 poss\u00edvel se surpreender bastante com os resultados, e o aprendizado pode ser repassado para as campanhas seguintes.<\/p>\n<p><strong>2. Siga um roteiro bem definido<\/strong><\/p>\n<p>Da mesma forma que os testes devem ser feitos de maneira minuciosa, \u00e9 preciso estabelecer um roteiro para fazer as mudan\u00e7as. Cada nova op\u00e7\u00e3o feita merece um acompanhamento especial, at\u00e9 que sejam realizadas mais altera\u00e7\u00f5es. \u00c9 preciso avaliar item por item e as mais variadas combina\u00e7\u00f5es poss\u00edveis, para saber qual ser\u00e1 a vers\u00e3o definitiva que ser\u00e1 usada para ser enviada aos clientes.<\/p>\n<p><strong>3. D\u00ea tempo ao tempo<\/strong><\/p>\n<p>O tempo \u00e9 um crit\u00e9rio importante por dois motivos: em primeiro lugar, para avaliar quantas convers\u00f5es foram efetuadas no per\u00edodo em que a pe\u00e7a esteve dispon\u00edvel ao p\u00fablico. Em segundo, pois devemos considerar as sazonalidades durante a exibi\u00e7\u00e3o do material. Por isso, leve em considera\u00e7\u00e3o um prazo de 30 dias para avaliar a verdadeira efic\u00e1cia de uma campanha, e evite, ao m\u00e1ximo, fazer testes em datas comemorativas ou sazonalidades, para n\u00e3o \u201cadulterar\u201d os testes.<\/p>\n<p><strong>4. Equipe especializada<\/strong><\/p>\n<p>Por fim, e n\u00e3o menos importante, \u00e9 fundamental que os testes sejam realizados por uma equipe fixa e especializada. Todos os resultados devem ser controlados por esses profissionais, que devem sempre oferecer relat\u00f3rios para a gest\u00e3o apontando os resultados. Mais importante ainda \u00e9 evitar a rotatividade de funcion\u00e1rios at\u00e9 que os testes estejam finalizados, o que certamente vai diminuir o retrabalho.<\/p>\n<p>Voc\u00ea costuma fazer testes A\/B no material disponibilizado ao p\u00fablico? N\u00e3o perca mais tempo e comece os experimentos. Para mais dicas, assine a nossa newsletter e receba conte\u00fado de primeira para otimizar as suas campanhas de e-mail marketing!<\/p>\n<p>&#8212;&#8212;-<\/p>\n<p>Artigo de Andr\u00e9 Metzen publicado originalmente no portal <a href=\"http:\/\/imasters.com.br\/midia-e-marketing-digital\/web-marketing\/dicas-para-aprender-mais-com-testes-ab\/\" target=\"_blank\" rel=\"noopener noreferrer\">iMasters<\/a>.\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\t\t\t\tUma das estrat\u00e9gias mais recomendadas para aprimorar a efic\u00e1cia das a\u00e7\u00f5es de comunica\u00e7\u00e3o e marketing de uma organiza\u00e7\u00e3o, aumentando, assim, as taxas de convers\u00e3o, \u00e9 a realiza\u00e7\u00e3o de testes A\/B.\t\t\t\t<\/p>\n","protected":false},"author":1,"featured_media":2818,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[99,146,158,204,210],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dicas para aprender mais com testes A\/B - Blog DialHost<\/title>\n<meta name=\"description\" content=\"Uma das estrat\u00e9gias recomendadas para aprimorar a efic\u00e1cia das a\u00e7\u00f5es de marketing, aumentando as taxas de convers\u00e3o, \u00e9 a realiza\u00e7\u00e3o de testes A\/B\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dicas para aprender mais com testes A\/B - Blog DialHost\" \/>\n<meta property=\"og:description\" content=\"Uma das estrat\u00e9gias recomendadas para aprimorar a efic\u00e1cia das a\u00e7\u00f5es de marketing, aumentando as taxas de convers\u00e3o, \u00e9 a realiza\u00e7\u00e3o de testes A\/B\" \/>\n<meta property=\"og:url\" content=\"\/blog\/dicas-para-aprender-mais-com-testes-ab\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog DialHost\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/DialHost\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/DialHost\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-22T13:08:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dialhost.com.br\/blog\/wp-content\/uploads\/2019\/04\/og-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dialhost\" \/>\n<meta name=\"twitter:site\" content=\"@dialhost\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#organization\",\"name\":\"DialHost Internet\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/\",\"sameAs\":[\"http:\/\/www.facebook.com\/DialHost\",\"https:\/\/www.instagram.com\/dialhost_oficial\/\",\"https:\/\/www.linkedin.com\/company\/dialhost-internet\",\"https:\/\/www.youtube.com\/channel\/UCAiqiX8IiqTSfA8wQhpzgXQ\",\"https:\/\/twitter.com\/dialhost\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/wp-content\/uploads\/2019\/03\/marca-dialhost.png\",\"width\":81,\"height\":81,\"caption\":\"DialHost Internet\"},\"image\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#website\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/\",\"name\":\"Blog DialHost\",\"description\":\"Os melhores conte\\u00fados sobre Desenvolvimento Web, Marketing e Neg\\u00f3cios\",\"publisher\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.dialhost.com.br\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/#webpage\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/\",\"name\":\"Dicas para aprender mais com testes A\/B - Blog DialHost\",\"isPartOf\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/#primaryimage\"},\"datePublished\":\"2014-09-22T13:08:53+00:00\",\"dateModified\":\"2014-09-22T13:08:53+00:00\",\"description\":\"Uma das estrat\\u00e9gias recomendadas para aprimorar a efic\\u00e1cia das a\\u00e7\\u00f5es de marketing, aumentando as taxas de convers\\u00e3o, \\u00e9 a realiza\\u00e7\\u00e3o de testes A\/B\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"\/blog\/\",\"url\":\"\/blog\/\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"\/blog\/dicas-para-aprender-mais-com-testes-ab\/\",\"url\":\"\/blog\/dicas-para-aprender-mais-com-testes-ab\/\",\"name\":\"Dicas para aprender mais com testes A\/B\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#\/schema\/person\/a0b10cbe35449dea173a06d4664f9fcc\"},\"headline\":\"Dicas para aprender mais com testes A\/B\",\"datePublished\":\"2014-09-22T13:08:53+00:00\",\"dateModified\":\"2014-09-22T13:08:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/#webpage\"},\"publisher\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/dicas-para-aprender-mais-com-testes-ab\/#primaryimage\"},\"keywords\":\"feed de parceiros,marketing,noticias,teste,usabilidade\",\"articleSection\":\"Dicas e Not\\u00edcias\",\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#\/schema\/person\/a0b10cbe35449dea173a06d4664f9fcc\",\"name\":\"DialHost Internet\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05feec2f99aef1c42b09aeaa637ee66f?s=96&r=g\",\"caption\":\"DialHost Internet\"},\"description\":\"H\\u00e1 mais de 18 anos proporcionando um servi\\u00e7o de hospedagem de sites voltado 100% na Experi\\u00eancia e Sucesso do Cliente, prezando a qualidade, transpar\\u00eancia e seguran\\u00e7a.\",\"sameAs\":[\"https:\/\/www.facebook.com\/DialHost\",\"https:\/\/www.instagram.com\/dialhost_oficial\/\",\"https:\/\/www.linkedin.com\/company\/dialhost-internet\",\"https:\/\/twitter.com\/dialhost\",\"https:\/\/www.youtube.com\/channel\/UCAiqiX8IiqTSfA8wQhpzgXQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/posts\/2772"}],"collection":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2772"}],"version-history":[{"count":0,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/posts\/2772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/media\/2818"}],"wp:attachment":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}