{"id":2743,"date":"2014-09-12T05:35:16","date_gmt":"2014-09-12T08:35:16","guid":{"rendered":"http:\/\/blog.dialhost.com.br\/?p=2743"},"modified":"2014-09-12T05:35:16","modified_gmt":"2014-09-12T08:35:16","slug":"aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo","status":"publish","type":"post","link":"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/","title":{"rendered":"Aumente a visibilidade do seu e-mail marketing com um design responsivo"},"content":{"rendered":"<figure id=\"attachment_2831\" aria-describedby=\"caption-attachment-2831\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"size-full wp-image-2831\" src=\"http:\/\/blog.dialhost.com.br\/wp-content\/uploads\/2014\/09\/visibilidade.jpg\" alt=\"E-mail marketing responsivo\" width=\"700\" height=\"260\" \/><figcaption id=\"caption-attachment-2831\" class=\"wp-caption-text\">Imagem ilustrativa: E-mail marketing responsivo<\/figcaption><\/figure>\n<p>N\u00e3o \u00e9 de hoje que as empresas investem massivamente na comunica\u00e7\u00e3o com os clientes divulgando suas novidades e promo\u00e7\u00f5es por e-mail marketing. No entanto, nos \u00faltimos anos os dispositivos m\u00f3veis cresceram expressivamente e, desta forma, os desktops e os notebooks deixaram de ser as \u00fanicas formas de acesso dos usu\u00e1rios.<\/p>\n<p>Segundo um estudo realizado pela F\/Nazca, em parceria com o Datafolha, mais de 43 milh\u00f5es de pessoas acessam a internet pelo celular no Brasil. Elas n\u00e3o esperam mais chegar em casa ou na mesa do trabalho para checar seus e-mails, fazer contatos e at\u00e9 mesmo realizar compras. Sendo assim, para aumentar a visibilidade do e-mail marketing, \u00e9 preciso ir al\u00e9m de um conte\u00fado atraente, inovador e direcionado: \u00e9 necess\u00e1rio que voc\u00ea se preocupe com a experi\u00eancia do usu\u00e1rio em todos os canais de acesso, principalmente, neste contexto, no mobile.<\/p>\n<p>Para isso, \u00e9 preciso estar atento ao desenvolvimento de suas campanhas com um design responsivo. Ou seja, que possa ser acessado e bem visualizado em qualquer plataforma, independentemente do tamanho das telas e das resolu\u00e7\u00f5es dos gadgets. Confira as dicas para aumentar a visibilidade do seu e-mail marketing e, consequentemente, os retorno sobre o investimento em suas campanhas:<\/p>\n<p><strong>Entenda as necessidades do mobile<\/strong><\/p>\n<p>N\u00e3o \u00e9 por que um conte\u00fado abre no dispositivo m\u00f3vel que ele est\u00e1 totalmente adequado \u00e0 plataforma utilizada. \u00c9 preciso que a acessibilidade e a usabilidade sejam pensadas com foco nestes meios de comunica\u00e7\u00e3o. A facilidade de abrir e compreender a mensagem de um e-mail marketing no smartphone, por exemplo, deve ser a mesma quando visualizada atrav\u00e9s de um notebook. Al\u00e9m disso, sua leitura e uso devem ser confort\u00e1veis ao usu\u00e1rio, principalmente no que compreende aos bot\u00f5es de Call to Action.<\/p>\n<p><strong>Facilite o acesso e abertura dos e-mails<\/strong><\/p>\n<p>Com a correria do dia a dia, \u00e9 nos dispositivos m\u00f3veis que as pessoas fazem o primeiro contato com seus e-mails. O que normalmente ocorre \u00e9 que elas recebem as mensagens, visualizam e, caso possua interesse, deixam para visualiz\u00e1-las novamente em outro momento. Portanto, se a mensagem n\u00e3o abre corretamente nestes dispositivos ou \u00e9 muito pesada, \u00e9 bastante prov\u00e1vel que ele v\u00e1 para a lixeira e n\u00e3o seja visto novamente.<\/p>\n<p><strong>Defina tamanhos adequados de fonte<\/strong><\/p>\n<p>Uma fonte muito grande ou pequena pode impactar negativamente na experi\u00eancia dos usu\u00e1rios, fazendo com que eles desistam de ler seu e-mail. Alguns aparelhos j\u00e1 possuem fun\u00e7\u00f5es espec\u00edficas para ajustar o tamanho da letra, no entanto, para n\u00e3o correr este risco, o ideal \u00e9 planejar o conte\u00fado para uma leitura agrad\u00e1vel.<\/p>\n<p><strong>Monitore o engajamento dos usu\u00e1rios<\/strong><\/p>\n<p>Existem diversas formas de mensurar quanto e de que forma o seu e-mail marketing tem atingido seu p\u00fablico-alvo. Desta forma, \u00e9 poss\u00edvel fazer ajustes e melhorias conforme as necessidades diagnosticadas garantindo, assim, uma maior assertividade e maior retorno sobre o investimento.<\/p>\n<p>Muitas empresas ainda est\u00e3o engatinhando na quest\u00e3o do design responsivo, mas as que j\u00e1 apostam nessa tend\u00eancia saem expressivamente na frente garantindo bons retornos por meio dos dispositivos m\u00f3veis. A realidade \u00e9 que cada vez mais as pessoas far\u00e3o seus acessos por dispositivos mobile e, por isso, \u00e9 fundamental que voc\u00ea desenvolva campanhas com design responsivo.<\/p>\n<p>Agora que voc\u00ea j\u00e1 conhece as vantagens do design responsivo para o desempenho de suas campanhas de e-mails marketing, que tal come\u00e7ar a utiliz\u00e1-lo? Caso voc\u00ea tenha ficado com d\u00favidas, deixe seu coment\u00e1rio abaixo!<\/p>\n<p>Texto de Andr\u00e9 Metzen, publicado originalmente no <a href=\"http:\/\/imasters.com.br\/midia-e-marketing-digital\/email-marketing\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/\" target=\"_blank\" rel=\"noopener noreferrer\">iMasters<\/a>.\t\t\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\t\t\t\tN\u00e3o \u00e9 de hoje que as empresas investem massivamente na comunica\u00e7\u00e3o com os clientes divulgando suas novidades e promo\u00e7\u00f5es por e-mail marketing. No entanto, nos \u00faltimos anos os dispositivos m\u00f3veis cresceram expressivamente e, desta forma, os desktops e os notebooks deixaram de ser as \u00fanicas formas de acesso dos usu\u00e1rios.\t\t\t\t<\/p>\n","protected":false},"author":1,"featured_media":2828,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[77,93,99,158],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aumente a visibilidade do seu e-mail marketing com um design responsivo - Blog DialHost<\/title>\n<meta name=\"description\" content=\"nos \u00faltimos anos os dispositivos m\u00f3veis cresceram e, desta forma, os desktops e os notebooks deixaram de ser as \u00fanicas formas de acesso dos usu\u00e1rios.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aumente a visibilidade do seu e-mail marketing com um design responsivo - Blog DialHost\" \/>\n<meta property=\"og:description\" content=\"nos \u00faltimos anos os dispositivos m\u00f3veis cresceram e, desta forma, os desktops e os notebooks deixaram de ser as \u00fanicas formas de acesso dos usu\u00e1rios.\" \/>\n<meta property=\"og:url\" content=\"\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog DialHost\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/DialHost\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/DialHost\" \/>\n<meta property=\"article:published_time\" content=\"2014-09-12T08:35:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dialhost.com.br\/blog\/wp-content\/uploads\/2019\/04\/og-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@dialhost\" \/>\n<meta name=\"twitter:site\" content=\"@dialhost\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#organization\",\"name\":\"DialHost Internet\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/\",\"sameAs\":[\"http:\/\/www.facebook.com\/DialHost\",\"https:\/\/www.instagram.com\/dialhost_oficial\/\",\"https:\/\/www.linkedin.com\/company\/dialhost-internet\",\"https:\/\/www.youtube.com\/channel\/UCAiqiX8IiqTSfA8wQhpzgXQ\",\"https:\/\/twitter.com\/dialhost\"],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#logo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/wp-content\/uploads\/2019\/03\/marca-dialhost.png\",\"width\":81,\"height\":81,\"caption\":\"DialHost Internet\"},\"image\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#website\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/\",\"name\":\"Blog DialHost\",\"description\":\"Os melhores conte\\u00fados sobre Desenvolvimento Web, Marketing e Neg\\u00f3cios\",\"publisher\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.dialhost.com.br\/blog\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/#webpage\",\"url\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/\",\"name\":\"Aumente a visibilidade do seu e-mail marketing com um design responsivo - Blog DialHost\",\"isPartOf\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/#primaryimage\"},\"datePublished\":\"2014-09-12T08:35:16+00:00\",\"dateModified\":\"2014-09-12T08:35:16+00:00\",\"description\":\"nos \\u00faltimos anos os dispositivos m\\u00f3veis cresceram e, desta forma, os desktops e os notebooks deixaram de ser as \\u00fanicas formas de acesso dos usu\\u00e1rios.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"\/blog\/\",\"url\":\"\/blog\/\",\"name\":\"In\\u00edcio\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@type\":\"WebPage\",\"@id\":\"\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/\",\"url\":\"\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/\",\"name\":\"Aumente a visibilidade do seu e-mail marketing com um design responsivo\"}}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#\/schema\/person\/a0b10cbe35449dea173a06d4664f9fcc\"},\"headline\":\"Aumente a visibilidade do seu e-mail marketing com um design responsivo\",\"datePublished\":\"2014-09-12T08:35:16+00:00\",\"dateModified\":\"2014-09-12T08:35:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/#webpage\"},\"publisher\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/aumente-visibilidade-seu-e-mail-marketing-com-um-design-responsivo\/#primaryimage\"},\"keywords\":\"design,email marketing,feed de parceiros,noticias\",\"articleSection\":\"Dicas e Not\\u00edcias\",\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#\/schema\/person\/a0b10cbe35449dea173a06d4664f9fcc\",\"name\":\"DialHost Internet\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.dialhost.com.br\/blog\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/05feec2f99aef1c42b09aeaa637ee66f?s=96&r=g\",\"caption\":\"DialHost Internet\"},\"description\":\"H\\u00e1 mais de 18 anos proporcionando um servi\\u00e7o de hospedagem de sites voltado 100% na Experi\\u00eancia e Sucesso do Cliente, prezando a qualidade, transpar\\u00eancia e seguran\\u00e7a.\",\"sameAs\":[\"https:\/\/www.facebook.com\/DialHost\",\"https:\/\/www.instagram.com\/dialhost_oficial\/\",\"https:\/\/www.linkedin.com\/company\/dialhost-internet\",\"https:\/\/twitter.com\/dialhost\",\"https:\/\/www.youtube.com\/channel\/UCAiqiX8IiqTSfA8wQhpzgXQ\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/posts\/2743"}],"collection":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/comments?post=2743"}],"version-history":[{"count":0,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/posts\/2743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/media\/2828"}],"wp:attachment":[{"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/media?parent=2743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/categories?post=2743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.dialhost.com.br\/blog\/wp-json\/wp\/v2\/tags?post=2743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}